{"id":172,"count":24,"description":"","link":"https:\/\/www.massageworksfw.com\/blog\/massage-therapy\/","name":"Massage Therapy","slug":"massage-therapy","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Massage Therapy Archives - Massage Works Therapy &amp; Spa Blog<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Massage Therapy Archives - Massage Works Therapy &amp; Spa Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.massageworksfw.com\/blog\/massage-therapy\/\" \/>\n<meta property=\"og:site_name\" content=\"Massage Works Therapy &amp; Spa Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.massageworksfw.com\\\/blog\\\/massage-therapy\\\/\",\"url\":\"https:\\\/\\\/www.massageworksfw.com\\\/blog\\\/massage-therapy\\\/\",\"name\":\"Massage Therapy Archives - Massage Works Therapy &amp; Spa Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.massageworksfw.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.massageworksfw.com\\\/blog\\\/massage-therapy\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.massageworksfw.com\\\/blog\\\/massage-therapy\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.massageworksfw.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Massage Therapy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.massageworksfw.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.massageworksfw.com\\\/blog\\\/\",\"name\":\"Massage Works Therapy &amp; Spa Blog\",\"description\":\"Massage Therapy in Fort Wayne\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.massageworksfw.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.massageworksfw.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.massageworksfw.com\\\/blog\\\/#organization\",\"name\":\"Massage Works Therapy Center\",\"url\":\"https:\\\/\\\/www.massageworksfw.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.massageworksfw.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.massageworksfw.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/cropped-MassageWorksWP.jpg\",\"contentUrl\":\"https:\\\/\\\/www.massageworksfw.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/cropped-MassageWorksWP.jpg\",\"width\":1785,\"height\":250,\"caption\":\"Massage Works Therapy Center\"},\"image\":{\"@id\":\"https:\\\/\\\/www.massageworksfw.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/massageworkstherapy\\\/\",\"https:\\\/\\\/www.instagram.com\\\/massageworksfw\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Massage Therapy Archives - Massage Works Therapy &amp; Spa Blog","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Massage Therapy Archives - Massage Works Therapy &amp; Spa Blog","og_url":"https:\/\/www.massageworksfw.com\/blog\/massage-therapy\/","og_site_name":"Massage Works Therapy &amp; Spa Blog","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.massageworksfw.com\/blog\/massage-therapy\/","url":"https:\/\/www.massageworksfw.com\/blog\/massage-therapy\/","name":"Massage Therapy Archives - Massage Works Therapy &amp; Spa Blog","isPartOf":{"@id":"https:\/\/www.massageworksfw.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.massageworksfw.com\/blog\/massage-therapy\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.massageworksfw.com\/blog\/massage-therapy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.massageworksfw.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Massage Therapy"}]},{"@type":"WebSite","@id":"https:\/\/www.massageworksfw.com\/blog\/#website","url":"https:\/\/www.massageworksfw.com\/blog\/","name":"Massage Works Therapy &amp; Spa Blog","description":"Massage Therapy in Fort Wayne","publisher":{"@id":"https:\/\/www.massageworksfw.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.massageworksfw.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.massageworksfw.com\/blog\/#organization","name":"Massage Works Therapy Center","url":"https:\/\/www.massageworksfw.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.massageworksfw.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.massageworksfw.com\/blog\/wp-content\/uploads\/2017\/04\/cropped-MassageWorksWP.jpg","contentUrl":"https:\/\/www.massageworksfw.com\/blog\/wp-content\/uploads\/2017\/04\/cropped-MassageWorksWP.jpg","width":1785,"height":250,"caption":"Massage Works Therapy Center"},"image":{"@id":"https:\/\/www.massageworksfw.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/massageworkstherapy\/","https:\/\/www.instagram.com\/massageworksfw\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.massageworksfw.com\/blog\/wp-json\/wp\/v2\/categories\/172","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.massageworksfw.com\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.massageworksfw.com\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.massageworksfw.com\/blog\/wp-json\/wp\/v2\/posts?categories=172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}